{"id":3829,"date":"2024-05-28T03:10:38","date_gmt":"2024-05-28T01:10:38","guid":{"rendered":"https:\/\/rollvis.com\/rv-hrv-vis-a-rouleaux-satellites\/"},"modified":"2025-09-05T06:02:50","modified_gmt":"2025-09-05T04:02:50","slug":"rv-hrv-vis-a-rouleaux-satellites","status":"publish","type":"page","link":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/","title":{"rendered":"RV\/HRV \u2013 Vis \u00e0 Rouleaux Satellites"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"3829\" class=\"elementor elementor-3829 elementor-3330\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5baa0d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5baa0d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63144cc\" data-id=\"63144cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3975c9 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"e3975c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">RV\/HRV \u2013 Vis a Rouleaux Satellites<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b86e4a8 elementor-widget elementor-widget-image\" data-id=\"b86e4a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"525\" height=\"295\" src=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-1024x576.jpg\" class=\"attachment-large size-large wp-image-2072\" alt=\"Planetary Roller Screw\" srcset=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-1024x576.jpg 1024w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-300x169.jpg 300w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-768x432.jpg 768w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-1536x864.jpg 1536w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-2048x1152.jpg 2048w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-scaled-e1711023330207.jpg 800w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a1d9340 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1d9340\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ce95471\" data-id=\"ce95471\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4e72d3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a4e72d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rollvis.com\/fr\/product-tables-rollvis-rv-planetary-roller-screw-en\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tableaux de donn\u00e9es vis RV<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abf556c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"abf556c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rollvis-embedded.partcommunity.com\/3d-cad-models\/rv-satellite-roller-screws-rollvis?info=rollvis%2Fsrs%2Frv_asmtab.prj&#038;hidePortlets=searchHeader&#038;languageIso=en\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RV Fichiers CAD<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-938d503\" data-id=\"938d503\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dcb1695 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"dcb1695\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rollvis.com\/fr\/product-tables-rollvis-hrv-planetary-roller-screw-en\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tableaux de donn\u00e9es vis HRV<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bb6923 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4bb6923\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rollvis-embedded.partcommunity.com\/3d-cad-models\/hrv-high-capacity-roller-screws-rollvis?info=rollvis%2Fsrs%2Fhrv_asmtab.prj&#038;hidePortlets=searchHeader&#038;languageIso=en\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HRV Fichiers CAD<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-386b209\" data-id=\"386b209\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87f7c8c elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"87f7c8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">RV\/HRV \u2013 Vis \u00e0 Rouleaux Satellites<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4b8529 elementor-widget elementor-widget-text-editor\" data-id=\"c4b8529\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les vis \u00e0 rouleaux satellites (ou vis \u00e0 rouleaux plan\u00e9taires) de haute pr\u00e9cision Rollvis transforment un mouvement de rotation, g\u00e9n\u00e9r\u00e9 par un moteur ou un r\u00e9ducteur, en un d\u00e9placement lin\u00e9aire capable de g\u00e9n\u00e9rer de tr\u00e8s fortes charges. Cela en offrant une grande pr\u00e9cision de positionnement, un rendement \u00e9lev\u00e9 et une fiabilit\u00e9 accrue. Leur conception permet une r\u00e9partition uniforme de la charge sur l\u2019ensemble des filets en contact ainsi qu\u2019une usure r\u00e9duite, ce qui en fait une alternative sup\u00e9rieure aux vis \u00e0 billes, aux syst\u00e8mes hydrauliques et aux entra\u00eenements par courroie ou par cha\u00eene. <\/p>\n<p>Lorsque l\u2019arbre de la vis \u00e0 rouleaux plan\u00e9taires RV tourne, les rouleaux (ou satellites), qui sont en contact \u00e0 la fois avec les filetages de la vis et ceux de l\u2019\u00e9crou, tournent en orbite autour de l\u2019axe de l\u2019\u00e9crou et se d\u00e9placent selon un mouvement lin\u00e9aire le long de l\u2019arbre de la vis, convertissant le mouvement de rotation initial en mouvement lin\u00e9aire de l\u2019\u00e9crou le long de la vis. Les vis \u00e0 rouleaux peuvent surpasser les vis \u00e0 billes dans presque tous les domaines. La s\u00e9rie HRV de vis \u00e0 rouleaux satellites Hautes Capacit\u00e9s, maximise quant \u00e0 elle les capacit\u00e9s de charges offertes pour un diam\u00e8tre de vis et une avance donn\u00e9es. <\/p>\n<p>Cette gamme de vis \u00e0 rouleaux plan\u00e9taires est disponible pour un diam\u00e8tre de vis sup\u00e9rieur ou \u00e9gal \u00e0 60mm.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5bb4c94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bb4c94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-455569c\" data-id=\"455569c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d13042 elementor-widget elementor-widget-video\" data-id=\"3d13042\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=3pMN3BqGk_o&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-031f1a4 elementor-widget elementor-widget-html\" data-id=\"031f1a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"application\/ld+json\">{\r\n  \"@context\": \"http:\/\/schema.org\",\r\n  \"@type\": \"VideoObject\",\r\n  \"name\": \"Planetary Roller Screws | Rollvis SA\",\r\n  \"description\": \"Rollvis high precision planetary (satellite) roller screws transfer a motor\u2019s rotational input into a heavy load capacity, high-precision, durable linear movement. Their design allows for even load distribution and reduced wear, making them a superior alternative to ball screws, hydraulics, and belt or chain drives. Check out our RV Planetary Roller Screws to learn more! https:\/\/rollvis.com\/rv-planetary-roller-screws\/  0:09 What Roller Screws Are Made Of 0:22 Critical Components of Roller Screws 0:30 Roller Screw Capabilities  0:40 How Roller Screws Are Made 1:10 How Roller Scres Work 1:40 Roller Screws Applicable to Customers' Needs 1:55 Benefits and Strengths of Roller Screws  As the RV planetary roller screw shaft rotates, the rollers, which are in contact with both the screw\u2019s threads and the nut\u2019s threads, also rotate and move in a planetary (orbiting) motion around the screw shaft, converting rotary motion into linear motion. Roller screws can outperform ball screws in nearly every category.  The HRV Series, heavy duty planetary roller screws, starts from shaft diameter 60mm and offers and even greater load capacity.\",\r\n  \"thumbnailUrl\": \"https:\/\/i.ytimg.com\/vi\/nqFigUZTgTc\/default.jpg\",\r\n  \"uploadDate\": \"2024-06-07T15:20:22Z\",\r\n  \"duration\": \"PT2M44S\",\r\n  \"embedUrl\": \"https:\/\/www.youtube.com\/embed\/nqFigUZTgTc\",\r\n  \"interactionCount\": \"398\"\r\n}<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0844fac\" data-id=\"0844fac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c071af elementor-widget elementor-widget-heading\" data-id=\"7c071af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">caract\u00e9ristiques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5619cfa elementor-widget elementor-widget-text-editor\" data-id=\"5619cfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"list-style-type: none;\"><ul><li>Diam\u00e8tres de vis allant de 3,5 mm \u00e0 210 mm<\/li><li>Avances par tour allant de 1,0 mm \u00e0 50 mm<\/li><li>Charges dynamiques de 3,9 kN [1 000 lb] \u00e0 3 800 kN [855 000 lb]<\/li><li>Engrenages de synchronisation internes<\/li><li>Les \u00e9crous, les rouleaux et les arbres sont rectifi\u00e9s avec pr\u00e9cision.<\/li><li>Construction enti\u00e8rement en acier de haute qualit\u00e9<\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1213e7d elementor-widget elementor-widget-heading\" data-id=\"1213e7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">b\u00e9n\u00e9fices<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0d8293 elementor-widget elementor-widget-text-editor\" data-id=\"e0d8293\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"list-style-type: none;\"><ul><li><strong>R\u00e9sistance:<\/strong> Les vis \u00e0 rouleaux industrielles utilisent des composants filet\u00e9s qui fournissent un grand nombre de points de contact avec l\u2019arbre de la vis, offrant ainsi une capacit\u00e9 de charge plus \u00e9lev\u00e9e que les vis \u00e0 billes de taille similaire<ul><li>Capacit\u00e9 de charge maximale tr\u00e8s \u00e9lev\u00e9e<\/li><li>La gamme <strong>HRV<\/strong>,vis \u00e0 rouleaux satellites \u00e0 hautes capacit\u00e9s, propose un \u00e9crou plus long et des g\u00e9om\u00e9tries internes optimis\u00e9es offrant des <strong>capacit\u00e9s de charges encore plus \u00e9lev\u00e9es<\/strong> pour un m\u00eame diam\u00e8tre d\u2019arbre et d\u2019\u00e9crou<\/li><li>R\u00e9sistance sup\u00e9rieure aux efforts et aux chocs<\/li><li>Longue dur\u00e9e de vie<\/li><li>Compacit\u00e9<\/li><\/ul><\/li><li><strong>Vitesse:<\/strong> La construction \u00e0 vis \u00e0 rouleaux permet des vitesses de fonctionnement sup\u00e9rieures \u00e0 2 m\/s et une acc\u00e9l\u00e9ration jusqu\u2019\u00e0 3G dans certains cas<\/li><li><strong>Efficacit\u00e9 : <\/strong>M\u00eame soumises \u00e0 des charges nominales extr\u00eamement \u00e9lev\u00e9es, les vis \u00e0 rouleaux offrent un rendement optimal<\/li><li><strong>Fiabilit\u00e9:<\/strong> Le m\u00e9canisme \u00e0 entra\u00eenement plan\u00e9taire offre une r\u00e9duction du bruit et des vibrations, ainsi qu\u2019un fonctionnement fiable avec <strong>peu de modes de d\u00e9faillance<\/strong><\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a2e3cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a2e3cd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e63971\" data-id=\"7e63971\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6679764 elementor-widget elementor-widget-spacer\" data-id=\"6679764\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6315d79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6315d79\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-325e900\" data-id=\"325e900\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef4f4cc elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"ef4f4cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Configurateur Dessin 3D CAD<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ad1ce0b elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ad1ce0b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-04b304e\" data-id=\"04b304e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ffecf41 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ffecf41\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rollvis-embedded.partcommunity.com\/3d-cad-models\/rv-satellite-roller-screws-rollvis?info=rollvis%2Fsrs%2Frv_asmtab.prj&#038;hidePortlets=searchHeader&#038;languageIso=en\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RV Fichiers CAD<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2e16727\" data-id=\"2e16727\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ae6b43 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0ae6b43\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rollvis-embedded.partcommunity.com\/3d-cad-models\/hrv-high-capacity-roller-screws-rollvis?info=rollvis%2Fsrs%2Fhrv_asmtab.prj&#038;hidePortlets=searchHeader&#038;languageIso=en\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">HRV Fichiers CAD<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6c624a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c624a1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-41abe1e\" data-id=\"41abe1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38c03b1 elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"38c03b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Configurateur Fichiers CAD mod\u00e8le RV<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-39c7fdd\" data-id=\"39c7fdd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d648037 elementor-align-center elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"d648037\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/rollvis-embedded.partcommunity.com\/3d-cad-models\/hrv-high-capacity-roller-screws-rollvis?info=rollvis%2Fsrs%2Fhrv_asmtab.prj&#038;hidePortlets=searchHeader&#038;languageIso=en\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Configurateur Fichiers CAD mod\u00e8le HRV<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-675480d elementor-widget elementor-widget-spacer\" data-id=\"675480d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98a36a1 elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"98a36a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<iframe src=\"https:\/\/rollvis-embedded.partcommunity.com\/3d-cad-models\/rv-satellite-roller-screws-rollvis?info=rollvis%2Fsrs%2Frv_asmtab.prj&amp;hidePortlets=searchHeader&amp;languageIso=en\" frameborder=\"0\" scrolling=\"yes\" width=\"10\" height=\"710\"><\/iframe>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a496156 elementor-widget elementor-widget-spacer\" data-id=\"a496156\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e8efd30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e8efd30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3dd4df\" data-id=\"e3dd4df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-206a610 elementor-widget elementor-widget-heading\" data-id=\"206a610\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Avantages<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bb40294 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb40294\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a1730ff\" data-id=\"a1730ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cc7d61d elementor-widget elementor-widget-image\" data-id=\"cc7d61d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Large-Press-shutterstock_115526239-1024x683.jpg\" class=\"attachment-large size-large wp-image-3262\" alt=\"Large Press Machine\" srcset=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Large-Press-shutterstock_115526239-1024x683.jpg 1024w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Large-Press-shutterstock_115526239-300x200.jpg 300w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Large-Press-shutterstock_115526239-768x512.jpg 768w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Large-Press-shutterstock_115526239-1536x1024.jpg 1536w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Large-Press-shutterstock_115526239.jpg 1555w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-aa1c560\" data-id=\"aa1c560\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9fa2abf elementor-widget elementor-widget-image\" data-id=\"9fa2abf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Electromechanical-Actuator-in-Application-shutterstock_2200334403-1024x682.jpg\" class=\"attachment-large size-large wp-image-3252\" alt=\"Electromechanical Actuator in Application\" srcset=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Electromechanical-Actuator-in-Application-shutterstock_2200334403-1024x682.jpg 1024w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Electromechanical-Actuator-in-Application-shutterstock_2200334403-300x200.jpg 300w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Electromechanical-Actuator-in-Application-shutterstock_2200334403-768x512.jpg 768w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Electromechanical-Actuator-in-Application-shutterstock_2200334403.jpg 1481w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3b790ed\" data-id=\"3b790ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6c0b48 elementor-widget elementor-widget-image\" data-id=\"e6c0b48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Prosthetic-Leg-shutterstock_1446076088-sm-1024x682.jpg\" class=\"attachment-large size-large wp-image-3268\" alt=\"Prosthetic Leg\" srcset=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Prosthetic-Leg-shutterstock_1446076088-sm-1024x682.jpg 1024w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Prosthetic-Leg-shutterstock_1446076088-sm-300x200.jpg 300w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Prosthetic-Leg-shutterstock_1446076088-sm-768x512.jpg 768w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Prosthetic-Leg-shutterstock_1446076088-sm-1536x1024.jpg 1536w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Prosthetic-Leg-shutterstock_1446076088-sm.jpg 1703w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-42f4095\" data-id=\"42f4095\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5368a39 elementor-widget elementor-widget-image\" data-id=\"5368a39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Robotic-Finger-shutterstock_1379131412-1024x683.jpg\" class=\"attachment-large size-large wp-image-3270\" alt=\"Robotic Finger touching human finger\" srcset=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Robotic-Finger-shutterstock_1379131412-1024x683.jpg 1024w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Robotic-Finger-shutterstock_1379131412-300x200.jpg 300w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Robotic-Finger-shutterstock_1379131412-768x512.jpg 768w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Robotic-Finger-shutterstock_1379131412-1536x1024.jpg 1536w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/Robotic-Finger-shutterstock_1379131412.jpg 1687w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f050ac7 elementor-widget elementor-widget-text-editor\" data-id=\"f050ac7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les clients peuvent profiter des caract\u00e9ristiques et des avantages des vis \u00e0 rouleaux plan\u00e9taires et des vis \u00e0 rouleaux plan\u00e9taires robustes de la mani\u00e8re suivante :<\/p><ul><li style=\"list-style-type: none;\"><ul><li>La <strong>longue dur\u00e9e de vie<\/strong> d\u2019une vis \u00e0 rouleaux plan\u00e9taires a r\u00e9duit les co\u00fbts de maintenance pour le client. Il n\u2019est pas rare que les vis RV aient une dur\u00e9e de vie 15 fois sup\u00e9rieure \u00e0 celle des vis \u00e0 billes.<\/li><li>La densit\u00e9 de charge <strong>compacte<\/strong> d\u2019une vis \u00e0 rouleaux permet aux machines et aux composants de machine d\u2019\u00eatre plus petits, ce qui permet d\u2019\u00e9conomiser de l\u2019espace et de l\u2019argent par rapport \u00e0 la conception globale de la machine. Cela est particuli\u00e8rement vrai avec les tr\u00e8s petites vis o\u00f9 la capacit\u00e9 de charge des vis \u00e0 billes est limit\u00e9e par la petite taille de la bille. <\/li><li>\u00c9lectrification : la <strong>densit\u00e9 de charge ultra \u00e9lev\u00e9e<\/strong> des vis de type HRV est essentielle pour pouvoir remplacer les syst\u00e8mes hydrauliques par une solution \u00e9lectrom\u00e9canique.<\/li><li>Les dimensions ext\u00e9rieures sont les m\u00eames quelle que soit la valeur du pas, ce qui rend les vis extr\u00eamement flexibles \u00e0 utiliser pour un concepteur de machines. Le <strong>HRV<\/strong> augmente la longueur de l\u2019\u00e9crou, mais l\u2019arbre et le diam\u00e8tre de l\u2019\u00e9crou restent les m\u00eames. <\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7649d37 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7649d37\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6032fcf\" data-id=\"6032fcf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-973574f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"973574f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f3b7706\" data-id=\"f3b7706\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0eb424 elementor-hidden-desktop elementor-widget elementor-widget-heading\" data-id=\"a0eb424\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Industrie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4577c7 elementor-widget elementor-widget-image\" data-id=\"f4577c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/rocket-shutterstock_1230117850-1024x683.jpg\" class=\"attachment-large size-large wp-image-3274\" alt=\"Rocket in Space\" srcset=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/rocket-shutterstock_1230117850-1024x683.jpg 1024w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/rocket-shutterstock_1230117850-300x200.jpg 300w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/rocket-shutterstock_1230117850-768x512.jpg 768w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/rocket-shutterstock_1230117850.jpg 1054w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f1d01b8\" data-id=\"f1d01b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a57e4cf elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"a57e4cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Industrie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faf204b elementor-widget elementor-widget-text-editor\" data-id=\"faf204b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"list-style-type: none;\"><ul><li><strong>Assemblage et Processus de fabrication :<\/strong> des volumes de production tr\u00e8s exigeants exigent un temps de disponibilit\u00e9 fiable et les vis \u00e0 rouleaux sont depuis longtemps au c\u0153ur des syst\u00e8mes utilis\u00e9s pour le soudage, le rivetage et le collage sur les cha\u00eenes d\u2019assemblage automobile.<\/li><li><strong>Formage et fa\u00e7onnage des m\u00e9taux <\/strong>: presses : le besoin de charges de pointe \u00e9lev\u00e9es est un facteur cl\u00e9 lors du formage, du poin\u00e7onnage ou du pliage de pi\u00e8ces m\u00e9talliques. Les vis \u00e0 rouleaux sont id\u00e9ales pour ce type d\u2019applications. <\/li><li><span style=\"font-weight: bold;\">A\u00e9ronautique :<\/span> Fiabilit\u00e9 dans des conditions extr\u00eames et gamme de mat\u00e9riaux de construction adapt\u00e9s au contr\u00f4le des composants des engins a\u00e9riens et spatiaux.<\/li><li><span style=\"font-weight: bold;\">P\u00e9trole et gaz :<\/span> Les \u00e9quipements et machines p\u00e9troliers et gaziers n\u00e9cessitent des vis \u00e0 rouleaux robustes, pr\u00e9cises et fiables pour l\u2019actionnement des vannes, les \u00e9quipements de forage et les v\u00e9rins de pompe.<\/li><li><span style=\"font-weight: bold;\">Dispositifs m\u00e9dicaux :<\/span> Lorsque des mouvements fluides, pr\u00e9cis et \u00e0 force \u00e9lev\u00e9e sont n\u00e9cessaires, les vis \u00e0 rouleaux sont s\u00e9lectionn\u00e9es.<\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f1af59d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1af59d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8ada011\" data-id=\"8ada011\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0a71ed elementor-widget elementor-widget-heading\" data-id=\"c0a71ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Applications<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-267a528 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"267a528\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-1024x683.jpg\" class=\"attachment-large size-large wp-image-3260\" alt=\"Injection Molding Machine\" srcset=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-1024x683.jpg 1024w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-300x200.jpg 300w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-768x512.jpg 768w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-1536x1024.jpg 1536w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-2048x1365.jpg 2048w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a331ea elementor-widget elementor-widget-text-editor\" data-id=\"2a331ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li style=\"list-style-type: none;\"><ul><li><strong>Actionneurs \u00e9lectrom\u00e9caniques :<\/strong> les vis \u00e0 rouleaux plan\u00e9taires sont au c\u0153ur des actionneurs \u00e9lectrom\u00e9caniques utilis\u00e9s lors du remplacement des syst\u00e8mes hydrauliques.<\/li><li><strong>Machines de moulage par injection :<\/strong> Contr\u00f4le pr\u00e9cis du mouvement, avec des charges \u00e9lev\u00e9es, pour produire des pi\u00e8ces en plastique de haute qualit\u00e9 avec des tol\u00e9rances serr\u00e9es et dans des volumes de production tr\u00e8s \u00e9lev\u00e9s.<\/li><li><b>Soudage par points :<\/b> La fiabilit\u00e9 sur des millions de cycles est essentielle pour la production automobile.<\/li><li><b>Op\u00e9rations de rivetage \u00e0 grand volume :<\/b> Vitesse \u00e9lev\u00e9e avec forces d\u2019impact \u00e9lev\u00e9es \u2013 Les vis \u00e0 rouleaux sont s\u00e9lectionn\u00e9es pour r\u00e9pondre \u00e0 un besoin de longue dur\u00e9e de vie.<\/li><li><b>Articulations robotiques :<\/b> Les vis \u00e0 rouleaux offrent une option d\u2019entreprise et de force \u00e9lev\u00e9e lorsque l\u2019on envisage un actionnement lin\u00e9aire dans le cadre de la robotique et des proth\u00e8ses modernes.<\/li><li><b>Formage, poin\u00e7onnage et pressage des m\u00e9taux :<\/b> Des charges \u00e9lev\u00e9es sont n\u00e9cessaires lors du formage, du pliage ou du poin\u00e7onnage de pi\u00e8ces m\u00e9talliques. Ces op\u00e9rations impliquent souvent un mouvement \u00e0 grande vitesse avec une charge d\u2019impact en fin de course. <br><\/li><\/ul><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fa36f1b\" data-id=\"fa36f1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ff1bc8 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"0ff1bc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"350\" src=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-1024x683.jpg\" class=\"attachment-large size-large wp-image-3260\" alt=\"Injection Molding Machine\" srcset=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-1024x683.jpg 1024w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-300x200.jpg 300w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-768x512.jpg 768w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-1536x1024.jpg 1536w, https:\/\/rollvis.com\/wp-content\/uploads\/2024\/05\/injection-molding-machine-shutterstock_179128457-2048x1365.jpg 2048w\" sizes=\"100vw\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac665bb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac665bb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d577dd\" data-id=\"2d577dd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a4f0ab elementor-widget elementor-widget-heading\" data-id=\"9a4f0ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Solutions d'automatisation innovantes pour les fabricants<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78d0f2b elementor-widget elementor-widget-text-editor\" data-id=\"78d0f2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Depuis 1970, Rollvis est un innovateur mondialement reconnu dans la conception et la fabrication de vis \u00e0 rouleaux plan\u00e9taires RV. Nos experts techniques peuvent vous aider \u00e0 personnaliser nos produits pour r\u00e9pondre \u00e0 vos exigences techniques sp\u00e9cifiques.  <\/p><p>Contactez-nous pour plus d\u2019informations aujourd\u2019hui. Rollvis est un producteur de vis \u00e0 rouleaux plan\u00e9taires de haute qualit\u00e9 certifi\u00e9 ISO 9001:2015 (industriel) et EN 9100:2018 (a\u00e9rospatiale). Contactez-nous d\u00e8s aujourd\u2019hui pour une consultation technique d\u2019experts sur votre application sp\u00e9cifique.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7636481 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7636481\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:900}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-lg\" href=\"https:\/\/rollvis.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez nos experts<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>RV\/HRV \u2013 Vis a Rouleaux Satellites Tableaux de donn\u00e9es vis RV RV Fichiers CAD Tableaux de donn\u00e9es vis HRV HRV Fichiers CAD RV\/HRV \u2013 Vis \u00e0 Rouleaux Satellites Les vis \u00e0 rouleaux satellites (ou vis \u00e0 rouleaux plan\u00e9taires) de haute pr\u00e9cision Rollvis transforment un mouvement de rotation, g\u00e9n\u00e9r\u00e9 par un moteur ou un r\u00e9ducteur, en &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;RV\/HRV \u2013 Vis \u00e0 Rouleaux Satellites&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"iawp_total_views":1208,"footnotes":""},"class_list":["post-3829","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vis \u00e0 Rouleaux Satellites de hautes precision | Rollvis SA<\/title>\n<meta name=\"description\" content=\"Rollvis propose des vis \u00e0 rouleaux plan\u00e9taires RV de haute pr\u00e9cision et des vis \u00e0 rouleaux plan\u00e9taires robustes, parfaites pour vos applications. Appelez aujourd&#039;hui!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vis \u00e0 Rouleaux Satellites de hautes precision | Rollvis SA\" \/>\n<meta property=\"og:description\" content=\"Rollvis propose des vis \u00e0 rouleaux plan\u00e9taires RV de haute pr\u00e9cision et des vis \u00e0 rouleaux plan\u00e9taires robustes, parfaites pour vos applications. Appelez aujourd&#039;hui!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/\" \/>\n<meta property=\"og:site_name\" content=\"Rollvis SA\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-05T04:02:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-scaled-e1709169362786.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/rv-hrv-vis-a-rouleaux-satellites\\\/\",\"url\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/rv-hrv-vis-a-rouleaux-satellites\\\/\",\"name\":\"Vis \u00e0 Rouleaux Satellites de hautes precision | Rollvis SA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/rv-hrv-vis-a-rouleaux-satellites\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/rv-hrv-vis-a-rouleaux-satellites\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/rollvis.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/RV-1024x576.jpg\",\"datePublished\":\"2024-05-28T01:10:38+00:00\",\"dateModified\":\"2025-09-05T04:02:50+00:00\",\"description\":\"Rollvis propose des vis \u00e0 rouleaux plan\u00e9taires RV de haute pr\u00e9cision et des vis \u00e0 rouleaux plan\u00e9taires robustes, parfaites pour vos applications. Appelez aujourd'hui!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/rv-hrv-vis-a-rouleaux-satellites\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/rollvis.com\\\/fr\\\/rv-hrv-vis-a-rouleaux-satellites\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/rv-hrv-vis-a-rouleaux-satellites\\\/#primaryimage\",\"url\":\"https:\\\/\\\/rollvis.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/RV-1024x576.jpg\",\"contentUrl\":\"https:\\\/\\\/rollvis.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/RV-1024x576.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/rv-hrv-vis-a-rouleaux-satellites\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RV\\\/HRV \u2013 Vis \u00e0 Rouleaux Satellites\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/\",\"name\":\"Rollvis SA\",\"description\":\"Planetary Roller Screws\",\"publisher\":{\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/#organization\",\"name\":\"Rollvis SA\",\"url\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rollvis.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-Rollvis-Logo-1.png\",\"contentUrl\":\"https:\\\/\\\/rollvis.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/cropped-Rollvis-Logo-1.png\",\"width\":384,\"height\":250,\"caption\":\"Rollvis SA\"},\"image\":{\"@id\":\"https:\\\/\\\/rollvis.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vis \u00e0 Rouleaux Satellites de hautes precision | Rollvis SA","description":"Rollvis propose des vis \u00e0 rouleaux plan\u00e9taires RV de haute pr\u00e9cision et des vis \u00e0 rouleaux plan\u00e9taires robustes, parfaites pour vos applications. Appelez aujourd'hui!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/","og_locale":"fr_FR","og_type":"article","og_title":"Vis \u00e0 Rouleaux Satellites de hautes precision | Rollvis SA","og_description":"Rollvis propose des vis \u00e0 rouleaux plan\u00e9taires RV de haute pr\u00e9cision et des vis \u00e0 rouleaux plan\u00e9taires robustes, parfaites pour vos applications. Appelez aujourd'hui!","og_url":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/","og_site_name":"Rollvis SA","article_modified_time":"2025-09-05T04:02:50+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-scaled-e1709169362786.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/","url":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/","name":"Vis \u00e0 Rouleaux Satellites de hautes precision | Rollvis SA","isPartOf":{"@id":"https:\/\/rollvis.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/#primaryimage"},"image":{"@id":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/#primaryimage"},"thumbnailUrl":"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-1024x576.jpg","datePublished":"2024-05-28T01:10:38+00:00","dateModified":"2025-09-05T04:02:50+00:00","description":"Rollvis propose des vis \u00e0 rouleaux plan\u00e9taires RV de haute pr\u00e9cision et des vis \u00e0 rouleaux plan\u00e9taires robustes, parfaites pour vos applications. Appelez aujourd'hui!","breadcrumb":{"@id":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/#primaryimage","url":"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-1024x576.jpg","contentUrl":"https:\/\/rollvis.com\/wp-content\/uploads\/2024\/02\/RV-1024x576.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/rollvis.com\/fr\/rv-hrv-vis-a-rouleaux-satellites\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/rollvis.com\/fr\/"},{"@type":"ListItem","position":2,"name":"RV\/HRV \u2013 Vis \u00e0 Rouleaux Satellites"}]},{"@type":"WebSite","@id":"https:\/\/rollvis.com\/fr\/#website","url":"https:\/\/rollvis.com\/fr\/","name":"Rollvis SA","description":"Planetary Roller Screws","publisher":{"@id":"https:\/\/rollvis.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rollvis.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/rollvis.com\/fr\/#organization","name":"Rollvis SA","url":"https:\/\/rollvis.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/rollvis.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/rollvis.com\/wp-content\/uploads\/2020\/04\/cropped-Rollvis-Logo-1.png","contentUrl":"https:\/\/rollvis.com\/wp-content\/uploads\/2020\/04\/cropped-Rollvis-Logo-1.png","width":384,"height":250,"caption":"Rollvis SA"},"image":{"@id":"https:\/\/rollvis.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rollvis.com\/fr\/wp-json\/wp\/v2\/pages\/3829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rollvis.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rollvis.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rollvis.com\/fr\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/rollvis.com\/fr\/wp-json\/wp\/v2\/comments?post=3829"}],"version-history":[{"count":56,"href":"https:\/\/rollvis.com\/fr\/wp-json\/wp\/v2\/pages\/3829\/revisions"}],"predecessor-version":[{"id":4806,"href":"https:\/\/rollvis.com\/fr\/wp-json\/wp\/v2\/pages\/3829\/revisions\/4806"}],"wp:attachment":[{"href":"https:\/\/rollvis.com\/fr\/wp-json\/wp\/v2\/media?parent=3829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}